{"id":23208,"date":"2023-04-05T08:02:39","date_gmt":"2023-04-05T08:02:39","guid":{"rendered":"https:\/\/www.suresmile.com\/fr-fr\/?page_id=23208"},"modified":"2023-09-29T15:25:50","modified_gmt":"2023-09-29T15:25:50","slug":"home","status":"publish","type":"page","link":"https:\/\/www.suresmile.com\/fr-fr\/home\/","title":{"rendered":"Home | SureSmile Aligner | Dentsply Sirona NEW"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"23208\" class=\"elementor elementor-23208\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dabfd40 elementor-section-height-min-height elementor-section-stretched elementor-hidden-tablet elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"dabfd40\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a033004\" data-id=\"a033004\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7ceed3 elementor-widget elementor-widget-heading\" data-id=\"e7ceed3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Aligneurs SureSmile<sup>\u00ae<\/sup>\u202f<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-448eb20 elementor-widget elementor-widget-text-editor\" data-id=\"448eb20\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pr\u00eat \u00e0 aimer votre sourire ?<br \/>D\u00e9couvrez SureSmile<sup>\u00ae<\/sup>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-91f2b5d elementor-section-height-min-height elementor-section-items-top elementor-section-stretched elementor-hidden-desktop elementor-section-boxed elementor-section-height-default\" data-id=\"91f2b5d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8e561a4\" data-id=\"8e561a4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69b2b8e elementor-widget elementor-widget-heading\" data-id=\"69b2b8e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Aligneurs SureSmile<sup>\u00ae<\/sup>\u202f<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db9db47 elementor-widget elementor-widget-text-editor\" data-id=\"db9db47\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPr\u00eat \u00e0 aimer votre sourire ?\nD\u00e9couvrez SureSmile<sup>\u00ae<\/sup>.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4049f3e\" data-id=\"4049f3e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bc49623 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc49623\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf9a7fc\" data-id=\"bf9a7fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2fa6f8 elementor-widget elementor-widget-heading\" data-id=\"c2fa6f8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L'exp\u00e9rience du traitement par aligneurs qui vous aide \u00e0 retrouver un sourire align\u00e9 et sain. <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1057fcd elementor-widget elementor-widget-text-editor\" data-id=\"1057fcd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si vous envisagez un traitement par aligneurs, nous savons que vous souhaitez obtenir les r\u00e9sultats que vous imaginez, dans les d\u00e9lais pr\u00e9vus, sans les goutti\u00e8res n&#8217;interf\u00e8rent avec votre quotidien.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7772d7e elementor-section-height-min-height elementor-section-items-bottom elementor-section-stretched elementor-section-full_width elementor-section-height-default\" data-id=\"7772d7e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7356612 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"7356612\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4f17649\" data-id=\"4f17649\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5d8185 elementor-widget elementor-widget-heading\" data-id=\"c5d8185\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Faites confiance \u00e0 SureSmile<sup>\u00ae<\/sup> <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bf8936 elementor-widget elementor-widget-text-editor\" data-id=\"6bf8936\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Votre plan de traitement personnalis\u00e9 est \u00e9labor\u00e9 par de v\u00e9ritables experts dentaires au laboratoire digital SureSmile<sup>\u00ae<\/sup>. Nos experts s&#8217;associent \u00e0 votre praticien pour comprendre votre sourire et les r\u00e9sultats souhait\u00e9s, afin d\u2019y r\u00e9pondre dans le temps imparti.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a23786 elementor-widget elementor-widget-text-editor\" data-id=\"9a23786\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>Un soutien pour rester sur la bonne voie.<\/strong> Votre praticien peut vous fournir le dispositif de vibration \u00e0 haute fr\u00e9quence SureSmile<sup>\u00ae<\/sup> VPro\u2122 \u00e0 utiliser seulement 5 minutes par jour avec les aligneurs. Cela peut am\u00e9liorer le confort du traitement et aider vos aligneurs \u00e0 s&#8217;adapter parfaitement.<a style=\"font-size: 16px; color: #ffffff;\" href=\"#source\"><sup>1-3<\/sup><\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b49c15 elementor-widget elementor-widget-text-editor\" data-id=\"5b49c15\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tVotre praticien suivra vos progr\u00e8s tout au long de votre parcours pour s&#8217;assurer que le traitement se d\u00e9roule comme pr\u00e9vu.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c09ed9 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3c09ed9\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-60578de\" data-id=\"60578de\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c0e908 elementor-widget elementor-widget-heading\" data-id=\"1c0e908\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le sourire que vous avez toujours voulu et qui convient \u00e0 votre budget <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9322a5d elementor-widget elementor-widget-text-editor\" data-id=\"9322a5d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Votre sourire est unique, tout comme l&#8217;est le traitement de votre sourire. Le co\u00fbt total du traitement d\u00e9pendra de vos objectifs et du plan personnalis\u00e9 sur lequel vous vous serez mis d&#8217;accord avec votre praticien.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1dc7c52 elementor-hidden-phone elementor-hidden-tablet\" data-id=\"1dc7c52\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2033f2a elementor-section-full_width elementor-section-stretched elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"2033f2a\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-359edaf\" data-id=\"359edaf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e28da3 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"0e28da3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.suresmile.com\/fr-fr\/suresmile-treatment-costs\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">EN SAVOIR PLUS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-106eba5 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"106eba5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.suresmile.com\/en-us\/wp-content\/uploads\/sites\/13\/2022\/07\/Image_SmileBudget.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-50cd7ca elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"50cd7ca\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f1fea16 elementor-hidden-phone elementor-hidden-tablet\" data-id=\"f1fea16\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6a8cfb9\" data-id=\"6a8cfb9\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f106a0d elementor-widget elementor-widget-heading\" data-id=\"f106a0d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Une exp\u00e9rience qui vous donnera le sourire <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e282d6 elementor-widget elementor-widget-text-editor\" data-id=\"2e282d6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSureSmile<sup>\u00ae<\/sup> vous aide \u00e0 retrouver un sourire sain et align\u00e9 tout en s&#8217;int\u00e9grant confortablement et facilement dans votre quotidien.<a href=\"#source\"><sup>4<\/sup><\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ce2630 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"5ce2630\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.suresmile.com\/fr-fr\/the-suresmile-system\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">EN SAVOIR PLUS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43eb3ee elementor-section-full_width elementor-section-stretched elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"43eb3ee\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-712962b\" data-id=\"712962b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fa32ef elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"4fa32ef\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.suresmile.com\/en-us\/wp-content\/uploads\/sites\/13\/2022\/07\/Image_Experience.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-626b25a elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"626b25a\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b6603f2\" data-id=\"b6603f2\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d34bb1 elementor-widget elementor-widget-heading\" data-id=\"5d34bb1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les patients aiment SureSmile<sup>\u00ae<\/sup> <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19ab21e elementor-widget elementor-widget-text-editor\" data-id=\"19ab21e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous c\u00e9l\u00e9brons le pouvoir contagieux du sourire. Nous avons d\u00e9j\u00e0 trait\u00e9 le sourire de plus de <span style=\"color: #0075c9;\"><strong>1 million<\/strong><\/span> patients.<a href=\"#source\"><sup>5<\/sup><\/a><\/p><p><strong>D\u00e9couvrez si SureSmile<sup>\u00ae<\/sup> est fait pour vous.\u00a0\u00a0<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d78a8d elementor-widget elementor-widget-button\" data-id=\"2d78a8d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.suresmile.com\/fr-fr\/is-suresmile-right-for-me\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">EN SAVOIR PLUS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-811c936 elementor-hidden-phone elementor-hidden-tablet\" data-id=\"811c936\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-858b7e5 elementor-section-full_width elementor-section-stretched elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"858b7e5\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f46abee\" data-id=\"f46abee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0674a8e elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"0674a8e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"841\" height=\"561\" src=\"https:\/\/www.suresmile.com\/fr-fr\/wp-content\/uploads\/sites\/39\/2023\/09\/2023-09-25_18_12_05_Image1M_091923-1-841x561.jpg\" class=\"attachment-large size-large wp-image-24052\" alt=\"\" srcset=\"https:\/\/www.suresmile.com\/fr-fr\/wp-content\/uploads\/sites\/39\/2023\/09\/2023-09-25_18_12_05_Image1M_091923-1-841x561.jpg 841w, https:\/\/www.suresmile.com\/fr-fr\/wp-content\/uploads\/sites\/39\/2023\/09\/2023-09-25_18_12_05_Image1M_091923-1-300x200.jpg 300w, https:\/\/www.suresmile.com\/fr-fr\/wp-content\/uploads\/sites\/39\/2023\/09\/2023-09-25_18_12_05_Image1M_091923-1-768x512.jpg 768w, https:\/\/www.suresmile.com\/fr-fr\/wp-content\/uploads\/sites\/39\/2023\/09\/2023-09-25_18_12_05_Image1M_091923-1.jpg 865w\" sizes=\"(max-width: 841px) 100vw, 841px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19b343b elementor-section-full_width elementor-section-stretched elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"19b343b\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5fb3a37\" data-id=\"5fb3a37\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab2ef8b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab2ef8b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5a701fe\" data-id=\"5a701fe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2fdd06 elementor-widget elementor-widget-menu-anchor\" data-id=\"c2fdd06\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"source\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09aea92 elementor-widget elementor-widget-text-editor\" data-id=\"09aea92\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ces dispositifs m\u00e9dicaux sont des produits de sant\u00e9 r\u00e9glement\u00e9s.<\/p><p>Les <strong>Aligneurs SureSmile<sup>\u00ae<\/sup><\/strong> sont des dispositifs m\u00e9dicaux sur mesure. Ce sont des goutti\u00e8res en plastique transparent de marque ESSIX utilis\u00e9es pour des traitements orthodontiques sur mesure. Ces produits ne peuvent \u00eatre prescrits qu&#8217;apr\u00e8s une consultation chez un professionnel de sant\u00e9 bucco-dentaire. Veuillez lire attentivement la notice. Fabricant : Orametrix Inc.<br \/><strong>SureSmile<sup>\u00ae<\/sup> VPro\u2122<\/strong> est un dispositif m\u00e9dical qui porte, au titre de la r\u00e9glementation, le marquage CE2797. Dispositif \u00e0 vibrations \u00e0 haute fr\u00e9quence (HFV) destin\u00e9 aux patients qui suivent un traitement orthodontique avec des aligneurs pour faciliter les mouvements mineurs des dents ant\u00e9rieures. Fabricant\u00a0: Dentsply LLC<br \/>Les <strong>Contentions SureSmile<sup>\u00ae<\/sup><\/strong> sont des dispositifs m\u00e9dicaux sur mesure. Ce sont des goutti\u00e8res en plastique transparent de marque ESSIX utilis\u00e9es pour la contention et la pr\u00e9vention des r\u00e9cidives \u00e0 la fin d\u2019un traitement orthodontique. Ces produits ne peuvent \u00eatre prescrits qu&#8217;apr\u00e8s une consultation chez un professionnel de sant\u00e9 bucco-dentaire. Veuillez lire attentivement la notice. Fabricant : Orametrix Inc. Rev : 05\/2023\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Aligneurs SureSmile\u00ae\u202f Pr\u00eat \u00e0 aimer votre sourire ?D\u00e9couvrez SureSmile\u00ae. Aligneurs SureSmile\u00ae\u202f Pr\u00eat \u00e0 aimer votre sourire ? D\u00e9couvrez SureSmile\u00ae. L&#8217;exp\u00e9rience du traitement par aligneurs qui vous aide \u00e0 retrouver un sourire align\u00e9 et sain. Si vous envisagez un traitement par aligneurs, nous savons que vous souhaitez obtenir les r\u00e9sultats que vous imaginez, dans les d\u00e9lais [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-23208","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aligneurs SureSmile | Traitement par aligneurs Dentsply Sirona pour le sourire de vos r\u00eaves | SureSmile<\/title>\n<meta name=\"description\" content=\"Obtenez le sourire dont vous avez toujours r\u00eav\u00e9 - avec nos aligneurs SureSmile, SureSmile VPro et nos contentions. En savoir plus !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.suresmile.com\/fr-fr\/home\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aligneurs SureSmile | Traitement par aligneurs Dentsply Sirona pour le sourire de vos r\u00eaves | SureSmile\" \/>\n<meta property=\"og:description\" content=\"Obtenez le sourire dont vous avez toujours r\u00eav\u00e9 - avec nos aligneurs SureSmile, SureSmile VPro et nos contentions. En savoir plus !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.suresmile.com\/fr-fr\/home\/\" \/>\n<meta property=\"og:site_name\" content=\"SureSmile France\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-29T15:25:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.suresmile.com\/en-us\/wp-content\/uploads\/sites\/13\/2022\/07\/Image_SmileBudget.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.suresmile.com\/fr-fr\/home\/\",\"url\":\"https:\/\/www.suresmile.com\/fr-fr\/home\/\",\"name\":\"Aligneurs SureSmile | Traitement par aligneurs Dentsply Sirona pour le sourire de vos r\u00eaves | SureSmile\",\"isPartOf\":{\"@id\":\"https:\/\/www.suresmile.com\/fr-fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.suresmile.com\/fr-fr\/home\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.suresmile.com\/fr-fr\/home\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.suresmile.com\/en-us\/wp-content\/uploads\/sites\/13\/2022\/07\/Image_SmileBudget.png\",\"datePublished\":\"2023-04-05T08:02:39+00:00\",\"dateModified\":\"2023-09-29T15:25:50+00:00\",\"description\":\"Obtenez le sourire dont vous avez toujours r\u00eav\u00e9 - avec nos aligneurs SureSmile, SureSmile VPro et nos contentions. En savoir plus !\",\"breadcrumb\":{\"@id\":\"https:\/\/www.suresmile.com\/fr-fr\/home\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.suresmile.com\/fr-fr\/home\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.suresmile.com\/fr-fr\/home\/#primaryimage\",\"url\":\"https:\/\/www.suresmile.com\/en-us\/wp-content\/uploads\/sites\/13\/2022\/07\/Image_SmileBudget.png\",\"contentUrl\":\"https:\/\/www.suresmile.com\/en-us\/wp-content\/uploads\/sites\/13\/2022\/07\/Image_SmileBudget.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.suresmile.com\/fr-fr\/home\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.suresmile.com\/fr-fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home | SureSmile Aligner | Dentsply Sirona NEW\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.suresmile.com\/fr-fr\/#website\",\"url\":\"https:\/\/www.suresmile.com\/fr-fr\/\",\"name\":\"SureSmile France\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.suresmile.com\/fr-fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.suresmile.com\/fr-fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.suresmile.com\/fr-fr\/#organization\",\"name\":\"SureSmile France\",\"url\":\"https:\/\/www.suresmile.com\/fr-fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.suresmile.com\/fr-fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.suresmile.com\/fr-fr\/wp-content\/uploads\/sites\/39\/2024\/11\/cropped-SS-Logo_Gray.png\",\"contentUrl\":\"https:\/\/www.suresmile.com\/fr-fr\/wp-content\/uploads\/sites\/39\/2024\/11\/cropped-SS-Logo_Gray.png\",\"width\":1200,\"height\":234,\"caption\":\"SureSmile France\"},\"image\":{\"@id\":\"https:\/\/www.suresmile.com\/fr-fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aligneurs SureSmile | Traitement par aligneurs Dentsply Sirona pour le sourire de vos r\u00eaves | SureSmile","description":"Obtenez le sourire dont vous avez toujours r\u00eav\u00e9 - avec nos aligneurs SureSmile, SureSmile VPro et nos contentions. En savoir plus !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.suresmile.com\/fr-fr\/home\/","og_locale":"en_US","og_type":"article","og_title":"Aligneurs SureSmile | Traitement par aligneurs Dentsply Sirona pour le sourire de vos r\u00eaves | SureSmile","og_description":"Obtenez le sourire dont vous avez toujours r\u00eav\u00e9 - avec nos aligneurs SureSmile, SureSmile VPro et nos contentions. En savoir plus !","og_url":"https:\/\/www.suresmile.com\/fr-fr\/home\/","og_site_name":"SureSmile France","article_modified_time":"2023-09-29T15:25:50+00:00","og_image":[{"url":"https:\/\/www.suresmile.com\/en-us\/wp-content\/uploads\/sites\/13\/2022\/07\/Image_SmileBudget.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.suresmile.com\/fr-fr\/home\/","url":"https:\/\/www.suresmile.com\/fr-fr\/home\/","name":"Aligneurs SureSmile | Traitement par aligneurs Dentsply Sirona pour le sourire de vos r\u00eaves | SureSmile","isPartOf":{"@id":"https:\/\/www.suresmile.com\/fr-fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.suresmile.com\/fr-fr\/home\/#primaryimage"},"image":{"@id":"https:\/\/www.suresmile.com\/fr-fr\/home\/#primaryimage"},"thumbnailUrl":"https:\/\/www.suresmile.com\/en-us\/wp-content\/uploads\/sites\/13\/2022\/07\/Image_SmileBudget.png","datePublished":"2023-04-05T08:02:39+00:00","dateModified":"2023-09-29T15:25:50+00:00","description":"Obtenez le sourire dont vous avez toujours r\u00eav\u00e9 - avec nos aligneurs SureSmile, SureSmile VPro et nos contentions. En savoir plus !","breadcrumb":{"@id":"https:\/\/www.suresmile.com\/fr-fr\/home\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.suresmile.com\/fr-fr\/home\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.suresmile.com\/fr-fr\/home\/#primaryimage","url":"https:\/\/www.suresmile.com\/en-us\/wp-content\/uploads\/sites\/13\/2022\/07\/Image_SmileBudget.png","contentUrl":"https:\/\/www.suresmile.com\/en-us\/wp-content\/uploads\/sites\/13\/2022\/07\/Image_SmileBudget.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.suresmile.com\/fr-fr\/home\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.suresmile.com\/fr-fr\/"},{"@type":"ListItem","position":2,"name":"Home | SureSmile Aligner | Dentsply Sirona NEW"}]},{"@type":"WebSite","@id":"https:\/\/www.suresmile.com\/fr-fr\/#website","url":"https:\/\/www.suresmile.com\/fr-fr\/","name":"SureSmile France","description":"","publisher":{"@id":"https:\/\/www.suresmile.com\/fr-fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.suresmile.com\/fr-fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.suresmile.com\/fr-fr\/#organization","name":"SureSmile France","url":"https:\/\/www.suresmile.com\/fr-fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.suresmile.com\/fr-fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.suresmile.com\/fr-fr\/wp-content\/uploads\/sites\/39\/2024\/11\/cropped-SS-Logo_Gray.png","contentUrl":"https:\/\/www.suresmile.com\/fr-fr\/wp-content\/uploads\/sites\/39\/2024\/11\/cropped-SS-Logo_Gray.png","width":1200,"height":234,"caption":"SureSmile France"},"image":{"@id":"https:\/\/www.suresmile.com\/fr-fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.suresmile.com\/fr-fr\/wp-json\/wp\/v2\/pages\/23208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.suresmile.com\/fr-fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.suresmile.com\/fr-fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.suresmile.com\/fr-fr\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.suresmile.com\/fr-fr\/wp-json\/wp\/v2\/comments?post=23208"}],"version-history":[{"count":82,"href":"https:\/\/www.suresmile.com\/fr-fr\/wp-json\/wp\/v2\/pages\/23208\/revisions"}],"predecessor-version":[{"id":24055,"href":"https:\/\/www.suresmile.com\/fr-fr\/wp-json\/wp\/v2\/pages\/23208\/revisions\/24055"}],"wp:attachment":[{"href":"https:\/\/www.suresmile.com\/fr-fr\/wp-json\/wp\/v2\/media?parent=23208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}